{"id":123,"count":1,"description":"","link":"https:\/\/www.facialcontest.com\/facialcontest\/tag\/lesbian-lovers\/","name":"Lesbian lovers","slug":"lesbian-lovers","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.facialcontest.com\/facialcontest\/wp-json\/wp\/v2\/tags\/123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.facialcontest.com\/facialcontest\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.facialcontest.com\/facialcontest\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.facialcontest.com\/facialcontest\/wp-json\/wp\/v2\/posts?tags=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}